{"id":15070,"date":"2024-02-20T07:30:15","date_gmt":"2024-02-20T05:30:15","guid":{"rendered":"https:\/\/www.jobs.ch\/de\/job-coach\/?p=15070"},"modified":"2024-04-16T10:58:41","modified_gmt":"2024-04-16T08:58:41","slug":"work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang","status":"publish","type":"post","link":"https:\/\/www.jobs.ch\/de\/job-coach\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\/","title":{"rendered":"Work-Life-Balance \u2013 so bringst du Arbeitsleben und Freizeit in Einklang"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":36,"featured_media":15071,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8,1],"tags":[877,1217,1356],"class_list":["post-15070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arbeitsalltag-gesundheit-work-life-balance","category-uncategorized","tag-mentale-gesundheit","tag-tipps","tag-work-life-balance"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Work-Life-Balance \u2013 was ist das und wie erreichst du sie?<\/title>\n<meta name=\"description\" content=\"Den Begriff Work-Life-Balance kennst du vielleicht schon. Hast du dich aber schon n\u00e4her mit ihm besch\u00e4ftigt? JobCloud kl\u00e4rt auf. Informiere dich jetzt!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jobs.ch\/de\/job-coach\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Work-Life-Balance \u2013 was ist das und wie erreichst du sie?\" \/>\n<meta property=\"og:description\" content=\"Den Begriff Work-Life-Balance kennst du vielleicht schon. Hast du dich aber schon n\u00e4her mit ihm besch\u00e4ftigt? JobCloud kl\u00e4rt auf. Informiere dich jetzt!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jobs.ch\/de\/job-coach\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\/\" \/>\n<meta property=\"og:site_name\" content=\"Willkommen im jobs.ch Job Coach mit News zu Jobs &amp; Bewerbungen\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-20T05:30:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-16T08:58:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jobs.ch\/de\/job-coach\/wp-content\/uploads\/2024\/02\/202-work-life-balance.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1025\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carmen B\u00fchler\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carmen B\u00fchler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\\\/\"},\"author\":{\"name\":\"Carmen B\u00fchler\",\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/#\\\/schema\\\/person\\\/170b9af6926b8fa260578118a72c501c\"},\"headline\":\"Work-Life-Balance \u2013 so bringst du Arbeitsleben und Freizeit in Einklang\",\"datePublished\":\"2024-02-20T05:30:15+00:00\",\"dateModified\":\"2024-04-16T08:58:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\\\/\"},\"wordCount\":9,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/202-work-life-balance.jpg\",\"keywords\":[\"mentale Gesundheit\",\"Tipps\",\"Work-Life-Balance\"],\"articleSection\":[\"Arbeitsalltag | Gesundheit | Work-Life-Balance\",\"Uncategorized\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\\\/\",\"url\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\\\/\",\"name\":\"Work-Life-Balance \u2013 was ist das und wie erreichst du sie?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/202-work-life-balance.jpg\",\"datePublished\":\"2024-02-20T05:30:15+00:00\",\"dateModified\":\"2024-04-16T08:58:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/#\\\/schema\\\/person\\\/170b9af6926b8fa260578118a72c501c\"},\"description\":\"Den Begriff Work-Life-Balance kennst du vielleicht schon. Hast du dich aber schon n\u00e4her mit ihm besch\u00e4ftigt? JobCloud kl\u00e4rt auf. Informiere dich jetzt!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/202-work-life-balance.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/202-work-life-balance.jpg\",\"width\":1025,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Job Coach\",\"item\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Work-Life-Balance \u2013 so bringst du Arbeitsleben und Freizeit in Einklang\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/#website\",\"url\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/\",\"name\":\"Willkommen im jobs.ch Job Coach mit News zu Jobs &amp; Bewerbungen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/#\\\/schema\\\/person\\\/170b9af6926b8fa260578118a72c501c\",\"name\":\"Carmen B\u00fchler\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/385df2b87668de6f41a4cba11f041d6b9b2ca98cd4c9381729185823d37f3218?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/385df2b87668de6f41a4cba11f041d6b9b2ca98cd4c9381729185823d37f3218?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/385df2b87668de6f41a4cba11f041d6b9b2ca98cd4c9381729185823d37f3218?s=96&d=mm&r=g\",\"caption\":\"Carmen B\u00fchler\"},\"url\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/author\\\/cbuehler\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Work-Life-Balance \u2013 was ist das und wie erreichst du sie?","description":"Den Begriff Work-Life-Balance kennst du vielleicht schon. Hast du dich aber schon n\u00e4her mit ihm besch\u00e4ftigt? JobCloud kl\u00e4rt auf. Informiere dich jetzt!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jobs.ch\/de\/job-coach\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\/","og_locale":"de_DE","og_type":"article","og_title":"Work-Life-Balance \u2013 was ist das und wie erreichst du sie?","og_description":"Den Begriff Work-Life-Balance kennst du vielleicht schon. Hast du dich aber schon n\u00e4her mit ihm besch\u00e4ftigt? JobCloud kl\u00e4rt auf. Informiere dich jetzt!","og_url":"https:\/\/www.jobs.ch\/de\/job-coach\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\/","og_site_name":"Willkommen im jobs.ch Job Coach mit News zu Jobs &amp; Bewerbungen","article_published_time":"2024-02-20T05:30:15+00:00","article_modified_time":"2024-04-16T08:58:41+00:00","og_image":[{"width":1025,"height":450,"url":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-content\/uploads\/2024\/02\/202-work-life-balance.jpg","type":"image\/jpeg"}],"author":"Carmen B\u00fchler","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Carmen B\u00fchler","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jobs.ch\/de\/job-coach\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\/#article","isPartOf":{"@id":"https:\/\/www.jobs.ch\/de\/job-coach\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\/"},"author":{"name":"Carmen B\u00fchler","@id":"https:\/\/www.jobs.ch\/de\/job-coach\/#\/schema\/person\/170b9af6926b8fa260578118a72c501c"},"headline":"Work-Life-Balance \u2013 so bringst du Arbeitsleben und Freizeit in Einklang","datePublished":"2024-02-20T05:30:15+00:00","dateModified":"2024-04-16T08:58:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jobs.ch\/de\/job-coach\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\/"},"wordCount":9,"commentCount":0,"image":{"@id":"https:\/\/www.jobs.ch\/de\/job-coach\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-content\/uploads\/2024\/02\/202-work-life-balance.jpg","keywords":["mentale Gesundheit","Tipps","Work-Life-Balance"],"articleSection":["Arbeitsalltag | Gesundheit | Work-Life-Balance","Uncategorized"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jobs.ch\/de\/job-coach\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jobs.ch\/de\/job-coach\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\/","url":"https:\/\/www.jobs.ch\/de\/job-coach\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\/","name":"Work-Life-Balance \u2013 was ist das und wie erreichst du sie?","isPartOf":{"@id":"https:\/\/www.jobs.ch\/de\/job-coach\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jobs.ch\/de\/job-coach\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\/#primaryimage"},"image":{"@id":"https:\/\/www.jobs.ch\/de\/job-coach\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-content\/uploads\/2024\/02\/202-work-life-balance.jpg","datePublished":"2024-02-20T05:30:15+00:00","dateModified":"2024-04-16T08:58:41+00:00","author":{"@id":"https:\/\/www.jobs.ch\/de\/job-coach\/#\/schema\/person\/170b9af6926b8fa260578118a72c501c"},"description":"Den Begriff Work-Life-Balance kennst du vielleicht schon. Hast du dich aber schon n\u00e4her mit ihm besch\u00e4ftigt? JobCloud kl\u00e4rt auf. Informiere dich jetzt!","breadcrumb":{"@id":"https:\/\/www.jobs.ch\/de\/job-coach\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jobs.ch\/de\/job-coach\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.jobs.ch\/de\/job-coach\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\/#primaryimage","url":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-content\/uploads\/2024\/02\/202-work-life-balance.jpg","contentUrl":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-content\/uploads\/2024\/02\/202-work-life-balance.jpg","width":1025,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.jobs.ch\/de\/job-coach\/work-life-balance-so-bringst-du-arbeitsleben-und-freizeit-in-einklang\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Job Coach","item":"https:\/\/www.jobs.ch\/de\/job-coach\/"},{"@type":"ListItem","position":2,"name":"Work-Life-Balance \u2013 so bringst du Arbeitsleben und Freizeit in Einklang"}]},{"@type":"WebSite","@id":"https:\/\/www.jobs.ch\/de\/job-coach\/#website","url":"https:\/\/www.jobs.ch\/de\/job-coach\/","name":"Willkommen im jobs.ch Job Coach mit News zu Jobs &amp; Bewerbungen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jobs.ch\/de\/job-coach\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.jobs.ch\/de\/job-coach\/#\/schema\/person\/170b9af6926b8fa260578118a72c501c","name":"Carmen B\u00fchler","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/385df2b87668de6f41a4cba11f041d6b9b2ca98cd4c9381729185823d37f3218?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/385df2b87668de6f41a4cba11f041d6b9b2ca98cd4c9381729185823d37f3218?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/385df2b87668de6f41a4cba11f041d6b9b2ca98cd4c9381729185823d37f3218?s=96&d=mm&r=g","caption":"Carmen B\u00fchler"},"url":"https:\/\/www.jobs.ch\/de\/job-coach\/author\/cbuehler\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-json\/wp\/v2\/posts\/15070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-json\/wp\/v2\/comments?post=15070"}],"version-history":[{"count":0,"href":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-json\/wp\/v2\/posts\/15070\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-json\/wp\/v2\/media\/15071"}],"wp:attachment":[{"href":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-json\/wp\/v2\/media?parent=15070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-json\/wp\/v2\/categories?post=15070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-json\/wp\/v2\/tags?post=15070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}