{"id":5664,"date":"2016-12-22T08:00:25","date_gmt":"2016-12-22T08:00:25","guid":{"rendered":"https:\/\/www.jobs.ch\/de\/job-coach\/?p=5664"},"modified":"2025-06-27T10:20:40","modified_gmt":"2025-06-27T08:20:40","slug":"christbaum-im-buro-arbeiten-den-weihnachtsferien","status":"publish","type":"post","link":"https:\/\/www.jobs.ch\/de\/job-coach\/christbaum-im-buro-arbeiten-den-weihnachtsferien\/","title":{"rendered":"Christbaum im B\u00fcro \u2013 arbeiten in den Weihnachtsferien"},"content":{"rendered":"<p>F\u00fcr viele sind Ferien \u00fcber die Weihnachtsfeiertage Pflicht. Andere haben w\u00e4hrend der Weihnachtszeit im Job vor allem Stress und k\u00f6nnen gar nicht an Ferien denken. Und dann gibt es jene, die keine freien Tage mehr haben und deshalb auch rund um die Feiertage im B\u00fcro oder in der Werkstatt sein m\u00fcssen. Wenn du auch dazugeh\u00f6rst \u2013 hier ein paar Tipps, damit du die Weihnachtsferien im Job \u00fcberstehst.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-5670\" src=\"https:\/\/www.jobs.ch\/de\/job-coach\/wp-content\/uploads\/2016\/12\/christmas-office_b-680x408.jpg\" alt=\"Christmas-Office_b\" width=\"680\" height=\"408\" \/><\/p>\n<h2><strong>Enjoy the silence<\/strong><\/h2>\n<p>Kein Chef, die meisten Kollegen sind in den Ferien \u2013 ist es nicht sch\u00f6n, einfach Mal die Ruhe im B\u00fcro zu geniessen? Du hast es dir verdient. Versuche, selbst im B\u00fcro etwas zu entspannen. G\u00f6nne dir Pausen und mach es dir mit den wenigen Kollegen, die genauso wie du am Arbeiten sind, gem\u00fctlich. Vielleicht bringst du ein paar Weihnachtsguetzli mit und sorgst mit einer Kerze auch im Office wenigstens f\u00fcr ein bisschen Weihnachtsstimmung. Nat\u00fcrlich sollst du mit den Pausen nicht \u00fcbertreiben und nur mit Nichtstun \u201ebesch\u00e4ftigt\u201c sein, aber in den meisten F\u00e4llen trifft es auf Verst\u00e4ndnis, wenn du in der Zeit zwischen Weihnachten und Neujahr einen Gang zur\u00fcckschaltest. Und irgendwie w\u00e4re es schade, die relativ stressfreien Tage f\u00fcr Ferien zu verschwenden \u2013 nimm sie doch wieder zu strengeren Zeiten, da kannst du sie besser gebrauchen.<\/p>\n<h2><strong>Das alte Jahr gut abschliessen<\/strong><\/h2>\n<p>Wer das alte Jahre gut beendet, der kann auch besser in das neue Jahr starten. N\u00fctze die ruhige Zeit, um mit einigen alten Dingen um B\u00fcro aufzur\u00e4umen. Schliesse Projekte ab, die du schon lange beenden wolltest und mache dich an Aufgaben, um die du dich w\u00e4hrend des Jahres nicht k\u00fcmmern konntest. Wie w\u00e4re es damit, deinen Arbeitsplatz wieder auf Vordermann zu bringen, deine Akten zu sortieren, unn\u00f6tigen Ballast zu entsorgen und Platz f\u00fcr Neues zu schaffen? So kannst du dann mit neuer Energie und das neue Jahr beginnen.<\/p>\n<h2><strong>Die gute Laune deiner Umgebung geniessen<\/strong><\/h2>\n<p>Komisch, aber irgendwie sind trotz m\u00f6glichem Stress in der Weihnachtszeit alle besser gelaunt. Die Feiertage sind meistens auch in der Arbeit ein Garant f\u00fcr gute Stimmung und selten werden so viele freundliche L\u00e4cheln und Nettigkeiten ausgetauscht wie jetzt. Wenn du Gl\u00fcck hast und in einer Branche arbeitest, wo du mit Trinkgeld rechnen kannst, dann freu dich auf die Grossz\u00fcgigkeit der Kunden um diese Zeit.<\/p>\n<h2><strong>Die Auszeit von der Familie nutzen<\/strong><\/h2>\n<p>Stell dir vor, du verbringst die ganzen Weihnachtsferien mit deiner Familie, deinen Eltern, Kindern, Tanten, Onkeln usw. F\u00fcr viele ist diese Vorstellung nicht besonders reizvoll, denn diese Tage sind High Season f\u00fcr Familienstreitereien, Beziehungsprobleme und dergleichen. Da ist es doch irgendwie angenehmer, wenn du an den Festtagen nur ein paar wenige Stunden mit deinen Lieben und den Rest der Zeit in der Arbeit verbringen kannst. Frei nach dem Motto weniger ist mehr. Wenn du dich bei Verwandten und Lieben rarmachst, dann sch\u00e4tzen sie gew\u00f6hnlich deine (kurze) Anwesenheit umso sehr und bevorzugen Harmonie anstelle von Streit.<\/p>\n<h2><strong>Bereits jetzt einen neuen Job suchen<\/strong><\/h2>\n<p>Hast du Lust auf neue Herausforderungen? Die Zeit nach den Weihnachtsferien geh\u00f6rt f\u00fcr die Jobsuche zu den wichtigsten Momenten im Jahr. Denn zu Beginn des neuen Jahres schreiben aufgrund der Jahres- und Budgetplanung besonders viele Unternehmen Jobs aus, werden Abteilungen umstrukturiert und neue Stellen geschaffen. Wenn du bereits jetzt mit der Jobsuche beginnst, dann bist du anderen Kandidaten einen Schritt voraus und kannst mit deiner fr\u00fchzeitigen Bewerbung bei den Unternehmen einen guten Eindruck machen \u2013 auch ein guter Moment f\u00fcr Spontanbewerbungen.<\/p>\n<p>Ab egal, ob du Ferien hast, in der Arbeit sitzt oder gerade auf Jobsuche bist, \u2013 g\u00f6nne dir ein paar ruhige Feiertage. F\u00fcr Stress hast du dann im n\u00e4chsten Jahr wieder genug Zeit!<\/p>\n<p>Eine gute Zeit, sich nach neuen Jobs umzusehen. Schaue dich auf <a href=\"https:\/\/www.jobs.ch\/de\/\" target=\"_blank\" rel=\"noopener noreferrer\">jobs.ch<\/a> \u2013 dem beliebtesten Jobportal der Deutschschweiz \u2013 um.<\/p>\n<p><span style=\"text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif; color: #ffffff; background: #bd081c no-repeat scroll 3px 50% \/ 14px 14px; cursor: pointer;\">Merken<\/span><\/p>\n<p><span style=\"text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif; color: #ffffff; background: #bd081c no-repeat scroll 3px 50% \/ 14px 14px; cursor: pointer;\">Merken<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr viele sind Ferien \u00fcber die Weihnachtsfeiertage Pflicht. Andere haben w\u00e4hrend [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12],"tags":[91,1636,1330,1331],"class_list":["post-5664","post","type-post","status-publish","format-standard","hentry","category-fun-facts-leichte-kost","tag-arbeiten-in-den-weihnachtsferien","tag-seasonal","tag-weihnachtsfeiertage","tag-weihnachtsferien"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Christbaum im B\u00fcro \u2013 arbeiten in den Weihnachtsferien - Willkommen im jobs.ch Job Coach mit News zu Jobs &amp; Bewerbungen<\/title>\n<meta name=\"description\" content=\"Wenn du zu jenen geh\u00f6rst, die in den Weihnachtsferien arbeiten m\u00fcssen \u2013 hier ein paar Tipps, damit du die Zeit gut \u00fcberstehst.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jobs.ch\/de\/job-coach\/christbaum-im-buro-arbeiten-den-weihnachtsferien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Christbaum im B\u00fcro \u2013 arbeiten in den Weihnachtsferien - Willkommen im jobs.ch Job Coach mit News zu Jobs &amp; Bewerbungen\" \/>\n<meta property=\"og:description\" content=\"Wenn du zu jenen geh\u00f6rst, die in den Weihnachtsferien arbeiten m\u00fcssen \u2013 hier ein paar Tipps, damit du die Zeit gut \u00fcberstehst.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jobs.ch\/de\/job-coach\/christbaum-im-buro-arbeiten-den-weihnachtsferien\/\" \/>\n<meta property=\"og:site_name\" content=\"Willkommen im jobs.ch Job Coach mit News zu Jobs &amp; Bewerbungen\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-22T08:00:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-27T08:20:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jobs.ch\/de\/job-coach\/wp-content\/uploads\/2016\/12\/christmas-office_b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1450\" \/>\n\t<meta property=\"og:image:height\" content=\"870\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mathias Steger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mathias Steger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/christbaum-im-buro-arbeiten-den-weihnachtsferien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/christbaum-im-buro-arbeiten-den-weihnachtsferien\\\/\"},\"author\":{\"name\":\"Mathias Steger\",\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/#\\\/schema\\\/person\\\/acb32532878cfb1d8aa9452d357ef859\"},\"headline\":\"Christbaum im B\u00fcro \u2013 arbeiten in den Weihnachtsferien\",\"datePublished\":\"2016-12-22T08:00:25+00:00\",\"dateModified\":\"2025-06-27T08:20:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/christbaum-im-buro-arbeiten-den-weihnachtsferien\\\/\"},\"wordCount\":656,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/christbaum-im-buro-arbeiten-den-weihnachtsferien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/christmas-office_b-680x408.jpg\",\"keywords\":[\"Arbeiten in den Weihnachtsferien\",\"seasonal\",\"Weihnachtsfeiertage\",\"Weihnachtsferien\"],\"articleSection\":[\"Fun Facts | Leichte Kost\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/christbaum-im-buro-arbeiten-den-weihnachtsferien\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/christbaum-im-buro-arbeiten-den-weihnachtsferien\\\/\",\"url\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/christbaum-im-buro-arbeiten-den-weihnachtsferien\\\/\",\"name\":\"Christbaum im B\u00fcro \u2013 arbeiten in den Weihnachtsferien - Willkommen im jobs.ch Job Coach mit News zu Jobs &amp; Bewerbungen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/christbaum-im-buro-arbeiten-den-weihnachtsferien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/christbaum-im-buro-arbeiten-den-weihnachtsferien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/christmas-office_b-680x408.jpg\",\"datePublished\":\"2016-12-22T08:00:25+00:00\",\"dateModified\":\"2025-06-27T08:20:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/#\\\/schema\\\/person\\\/acb32532878cfb1d8aa9452d357ef859\"},\"description\":\"Wenn du zu jenen geh\u00f6rst, die in den Weihnachtsferien arbeiten m\u00fcssen \u2013 hier ein paar Tipps, damit du die Zeit gut \u00fcberstehst.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/christbaum-im-buro-arbeiten-den-weihnachtsferien\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/christbaum-im-buro-arbeiten-den-weihnachtsferien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/christbaum-im-buro-arbeiten-den-weihnachtsferien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/christmas-office_b-680x408.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/christmas-office_b-680x408.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/christbaum-im-buro-arbeiten-den-weihnachtsferien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Job Coach\",\"item\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Christbaum im B\u00fcro \u2013 arbeiten in den Weihnachtsferien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/#website\",\"url\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/\",\"name\":\"Willkommen im jobs.ch Job Coach mit News zu Jobs &amp; Bewerbungen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/#\\\/schema\\\/person\\\/acb32532878cfb1d8aa9452d357ef859\",\"name\":\"Mathias Steger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/mathias-steger_avatar-96x96.jpeg\",\"url\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/mathias-steger_avatar-96x96.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/mathias-steger_avatar-96x96.jpeg\",\"caption\":\"Mathias Steger\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mathias-steger-52164a11b\\\/\"],\"url\":\"https:\\\/\\\/www.jobs.ch\\\/de\\\/job-coach\\\/author\\\/mathias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Christbaum im B\u00fcro \u2013 arbeiten in den Weihnachtsferien - Willkommen im jobs.ch Job Coach mit News zu Jobs &amp; Bewerbungen","description":"Wenn du zu jenen geh\u00f6rst, die in den Weihnachtsferien arbeiten m\u00fcssen \u2013 hier ein paar Tipps, damit du die Zeit gut \u00fcberstehst.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jobs.ch\/de\/job-coach\/christbaum-im-buro-arbeiten-den-weihnachtsferien\/","og_locale":"de_DE","og_type":"article","og_title":"Christbaum im B\u00fcro \u2013 arbeiten in den Weihnachtsferien - Willkommen im jobs.ch Job Coach mit News zu Jobs &amp; Bewerbungen","og_description":"Wenn du zu jenen geh\u00f6rst, die in den Weihnachtsferien arbeiten m\u00fcssen \u2013 hier ein paar Tipps, damit du die Zeit gut \u00fcberstehst.","og_url":"https:\/\/www.jobs.ch\/de\/job-coach\/christbaum-im-buro-arbeiten-den-weihnachtsferien\/","og_site_name":"Willkommen im jobs.ch Job Coach mit News zu Jobs &amp; Bewerbungen","article_published_time":"2016-12-22T08:00:25+00:00","article_modified_time":"2025-06-27T08:20:40+00:00","og_image":[{"width":1450,"height":870,"url":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-content\/uploads\/2016\/12\/christmas-office_b.jpg","type":"image\/jpeg"}],"author":"Mathias Steger","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Mathias Steger","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jobs.ch\/de\/job-coach\/christbaum-im-buro-arbeiten-den-weihnachtsferien\/#article","isPartOf":{"@id":"https:\/\/www.jobs.ch\/de\/job-coach\/christbaum-im-buro-arbeiten-den-weihnachtsferien\/"},"author":{"name":"Mathias Steger","@id":"https:\/\/www.jobs.ch\/de\/job-coach\/#\/schema\/person\/acb32532878cfb1d8aa9452d357ef859"},"headline":"Christbaum im B\u00fcro \u2013 arbeiten in den Weihnachtsferien","datePublished":"2016-12-22T08:00:25+00:00","dateModified":"2025-06-27T08:20:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jobs.ch\/de\/job-coach\/christbaum-im-buro-arbeiten-den-weihnachtsferien\/"},"wordCount":656,"commentCount":0,"image":{"@id":"https:\/\/www.jobs.ch\/de\/job-coach\/christbaum-im-buro-arbeiten-den-weihnachtsferien\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-content\/uploads\/2016\/12\/christmas-office_b-680x408.jpg","keywords":["Arbeiten in den Weihnachtsferien","seasonal","Weihnachtsfeiertage","Weihnachtsferien"],"articleSection":["Fun Facts | Leichte Kost"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jobs.ch\/de\/job-coach\/christbaum-im-buro-arbeiten-den-weihnachtsferien\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jobs.ch\/de\/job-coach\/christbaum-im-buro-arbeiten-den-weihnachtsferien\/","url":"https:\/\/www.jobs.ch\/de\/job-coach\/christbaum-im-buro-arbeiten-den-weihnachtsferien\/","name":"Christbaum im B\u00fcro \u2013 arbeiten in den Weihnachtsferien - Willkommen im jobs.ch Job Coach mit News zu Jobs &amp; Bewerbungen","isPartOf":{"@id":"https:\/\/www.jobs.ch\/de\/job-coach\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jobs.ch\/de\/job-coach\/christbaum-im-buro-arbeiten-den-weihnachtsferien\/#primaryimage"},"image":{"@id":"https:\/\/www.jobs.ch\/de\/job-coach\/christbaum-im-buro-arbeiten-den-weihnachtsferien\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-content\/uploads\/2016\/12\/christmas-office_b-680x408.jpg","datePublished":"2016-12-22T08:00:25+00:00","dateModified":"2025-06-27T08:20:40+00:00","author":{"@id":"https:\/\/www.jobs.ch\/de\/job-coach\/#\/schema\/person\/acb32532878cfb1d8aa9452d357ef859"},"description":"Wenn du zu jenen geh\u00f6rst, die in den Weihnachtsferien arbeiten m\u00fcssen \u2013 hier ein paar Tipps, damit du die Zeit gut \u00fcberstehst.","breadcrumb":{"@id":"https:\/\/www.jobs.ch\/de\/job-coach\/christbaum-im-buro-arbeiten-den-weihnachtsferien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jobs.ch\/de\/job-coach\/christbaum-im-buro-arbeiten-den-weihnachtsferien\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.jobs.ch\/de\/job-coach\/christbaum-im-buro-arbeiten-den-weihnachtsferien\/#primaryimage","url":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-content\/uploads\/2016\/12\/christmas-office_b-680x408.jpg","contentUrl":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-content\/uploads\/2016\/12\/christmas-office_b-680x408.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jobs.ch\/de\/job-coach\/christbaum-im-buro-arbeiten-den-weihnachtsferien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Job Coach","item":"https:\/\/www.jobs.ch\/de\/job-coach\/"},{"@type":"ListItem","position":2,"name":"Christbaum im B\u00fcro \u2013 arbeiten in den Weihnachtsferien"}]},{"@type":"WebSite","@id":"https:\/\/www.jobs.ch\/de\/job-coach\/#website","url":"https:\/\/www.jobs.ch\/de\/job-coach\/","name":"Willkommen im jobs.ch Job Coach mit News zu Jobs &amp; Bewerbungen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jobs.ch\/de\/job-coach\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.jobs.ch\/de\/job-coach\/#\/schema\/person\/acb32532878cfb1d8aa9452d357ef859","name":"Mathias Steger","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-content\/uploads\/2022\/09\/mathias-steger_avatar-96x96.jpeg","url":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-content\/uploads\/2022\/09\/mathias-steger_avatar-96x96.jpeg","contentUrl":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-content\/uploads\/2022\/09\/mathias-steger_avatar-96x96.jpeg","caption":"Mathias Steger"},"sameAs":["https:\/\/www.linkedin.com\/in\/mathias-steger-52164a11b\/"],"url":"https:\/\/www.jobs.ch\/de\/job-coach\/author\/mathias\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-json\/wp\/v2\/posts\/5664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-json\/wp\/v2\/comments?post=5664"}],"version-history":[{"count":0,"href":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-json\/wp\/v2\/posts\/5664\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-json\/wp\/v2\/media?parent=5664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-json\/wp\/v2\/categories?post=5664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jobs.ch\/de\/job-coach\/wp-json\/wp\/v2\/tags?post=5664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}